{
    "id": 1038,
    "date": "2021-09-01T13:49:53",
    "date_gmt": "2021-09-01T13:49:53",
    "guid": {
        "rendered": "http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?page_id=1038"
    },
    "modified": "2025-04-25T18:37:20",
    "modified_gmt": "2025-04-25T14:37:20",
    "slug": "home",
    "status": "publish",
    "type": "page",
    "link": "https:\/\/abccae.com\/en_us\/",
    "title": {
        "rendered": "Home"
    },
    "content": {
        "rendered": "<div data-elementor-type=\"wp-page\" data-elementor-id=\"1038\" class=\"elementor elementor-1038\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5db1223 e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"5db1223\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cb49a7 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"8cb49a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"#!trpst#trp-gettext data-trpgettextoriginal=7425#!trpen#1 of 2#!trpst#\/trp-gettext#!trpen#\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/Copy-of-Abcc-2_page-0001-scaled.jpg\" alt=\"Copy of Abcc 2_page-0001\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"#!trpst#trp-gettext data-trpgettextoriginal=7425#!trpen#2 of 2#!trpst#\/trp-gettext#!trpen#\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/Abcc-2_page-0001-scaled.jpg\" alt=\"Abcc 2_page-0001\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4889c2b e-flex e-con-boxed e-con e-parent\" data-id=\"4889c2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ad56107 e-con-full e-flex e-con e-child\" data-id=\"ad56107\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7bcb123 elementor-widget elementor-widget-image\" data-id=\"7bcb123\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/abcc-ae.com\/courses\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/2.png\" class=\"attachment-large size-large wp-image-16288\" alt=\"\" srcset=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/2.png 500w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/2-150x150.png 150w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/2-300x300.png 300w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/2-12x12.png 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-654ca70 e-con-full e-flex e-con e-child\" data-id=\"654ca70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06e3540 elementor-widget elementor-widget-image\" data-id=\"06e3540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/abcc-ae.com\/consultancy\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/1.png\" class=\"attachment-large size-large wp-image-16287\" alt=\"\" srcset=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/1.png 500w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/1-150x150.png 150w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/1-300x300.png 300w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/1-12x12.png 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12b1029 e-con-full e-flex e-con e-child\" data-id=\"12b1029\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4a9748 elementor-widget elementor-widget-image\" data-id=\"f4a9748\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/abcc-ae.com\/current-subscribers\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/3.png\" class=\"attachment-large size-large wp-image-16289\" alt=\"\" srcset=\"https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/3.png 500w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/3-150x150.png 150w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/3-300x300.png 300w, https:\/\/abccae.com\/wp-content\/uploads\/2025\/04\/3-12x12.png 12w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>",
        "protected": false
    },
    "excerpt": {
        "rendered": "",
        "protected": false
    },
    "author": 2,
    "featured_media": 0,
    "parent": 0,
    "menu_order": 0,
    "comment_status": "closed",
    "ping_status": "closed",
    "template": "",
    "meta": {
        "footnotes": ""
    },
    "class_list": [
        "post-1038",
        "page",
        "type-page",
        "status-publish",
        "hentry"
    ],
    "_links": {
        "self": [
            {
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/pages\/1038",
                "targetHints": {
                    "allow": [
                        "GET"
                    ]
                }
            }
        ],
        "collection": [
            {
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/pages"
            }
        ],
        "about": [
            {
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/types\/page"
            }
        ],
        "author": [
            {
                "embeddable": true,
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/users\/2"
            }
        ],
        "replies": [
            {
                "embeddable": true,
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/comments?post=1038"
            }
        ],
        "version-history": [
            {
                "count": 289,
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/pages\/1038\/revisions"
            }
        ],
        "predecessor-version": [
            {
                "id": 16704,
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/pages\/1038\/revisions\/16704"
            }
        ],
        "wp:attachment": [
            {
                "href": "https:\/\/abccae.com\/en_us\/wp-json\/wp\/v2\/media?parent=1038"
            }
        ],
        "curies": [
            {
                "name": "wp",
                "href": "https:\/\/api.w.org\/{rel}",
                "templated": true
            }
        ]
    }
}